{"id":76,"date":"2017-04-06T12:52:51","date_gmt":"2017-04-06T12:52:51","guid":{"rendered":"http:\/\/williamson.dv.themerex.net\/?page_id=76"},"modified":"2021-10-17T20:01:18","modified_gmt":"2021-10-17T20:01:18","slug":"contacts","status":"publish","type":"page","link":"https:\/\/kanzlei-taner.de\/tr\/contacts\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid vc_custom_1527690588959 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12 sc_layouts_column_icons_position_left\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 4em\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Datenschutz<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 4em\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div id=\"sc_content_571663170\"\n\t\tclass=\"sc_content color_style_default sc_content_default sc_float_center p70\"><div class=\"sc_content_container\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"cms_paragraph\">\n<h3>Allgemeine Hinweise<\/h3>\n<p>&nbsp;<\/p>\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n<p><strong>Datenerfassung auf unserer Website<\/strong><br \/>\nWer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<br \/>\nDie Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Impressum dieser Website entnehmen.<\/p>\n<p><strong>Wie erfassen wir Ihre Daten?<\/strong><br \/>\nIhre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.B. um Daten handeln, die Sie in ein Kontaktformular eingeben. Andere Daten werden automatisch beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie unsere Website betreten.<\/p>\n<p><strong>Wof\u00fcr nutzen wir Ihre Daten?<\/strong><br \/>\nEin Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n<p><strong>Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/strong><br \/>\nSie haben jederzeit das Recht unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung, Sperrung oder L\u00f6schung dieser Daten zu verlangen. Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n<p>Au\u00dferdem haben Sie das Recht, unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Details hierzu entnehmen Sie der Datenschutzerkl\u00e4rung unter \u201eRecht auf Einschr\u00e4nkung der Verarbeitung\u201c.<\/p>\n<p><strong>Analyse-Tools und Tools von Drittanbietern<\/strong><br \/>\nBeim Besuch unserer Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit Cookies und mit sogenannten Analyseprogrammen. Die Analyse Ihres Surf-Verhaltens erfolgt in der Regel anonym; das Surf-Verhalten kann nicht zu Ihnen zur\u00fcckverfolgt werden. Sie k\u00f6nnen dieser Analyse widersprechen oder sie durch die Nichtbenutzung bestimmter Tools verhindern. Detaillierte Informationen dazu finden Sie in der folgenden Datenschutzerkl\u00e4rung.<\/p>\n<p>Sie k\u00f6nnen dieser Analyse widersprechen. \u00dcber die Widerspruchsm\u00f6glichkeiten werden wir Sie in dieser Datenschutzerkl\u00e4rung informieren.<\/p>\n<p>&nbsp;<\/p>\n<h3>Allgemeine Hinweise und Pflichtinformationen<\/h3>\n<p>&nbsp;<\/p>\n<p><strong>Datenschutz<\/strong><\/p>\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n<p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Hinweis zur verantwortlichen Stelle<\/strong><\/p>\n<p>Die Verantwortliche im Sinne der Datenschutzgesetze ist die:<\/p>\n<div class=\"cms_paragraph\"><strong>Kanzlei Taner-\u00d6zbelli<\/strong><br \/>\nSevinc Taner-\u00d6zbelli<br \/>\nPlinganserstra\u00dfe 51<br \/>\n81369 M\u00fcnchen<\/div>\n<div><\/div>\n<div class=\"cms_paragraph\">Telefon:\u00a0<a href=\"https:\/\/www.google.com\/search?q=rechtsanw%C3%A4ltin+sevinc+taner&amp;oq=rechtsanw%C3%A4ltin+sevinc+taner&amp;aqs=chrome..69i57j0i22i30j69i60l3.7751j0j9&amp;sourceid=chrome&amp;ie=UTF-8#\" data-dtype=\"d3ifr\" data-local-attribute=\"d3ph\" data-ved=\"2ahUKEwidq6Cxj9LzAhWKzaQKHcC1DkIQkAgoAHoECDQQAw\"><span aria-label=\"089 41619235 anrufen\">089 41619235<\/span><\/a><\/div>\n<div class=\"cms_paragraph\">\n<p>E-Mail:\u00a0<a href=\"mailto:info@kanzlei-taner.de\">info@kanzlei-taner.de<\/a><br \/>\nInternet: www.kanzlei-taner.de<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p class=\"Text-Title\"><strong>Widerspruchsrecht gegen die Datenerhebung in besonderen F\u00e4llen sowie gegen Direktwerbung (Art. 21 DSGVO)<\/strong><\/p>\n<p>Wenn die Datenverarbeitung auf Grundlage von Art. 6 Abs. 1 lit. e oder f DSGVO erfolgt, haben Sie jederzeit das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, gegen die Verarbeitung Ihrer personenbezogenen Daten Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling. Die jeweilige Rechtsgrundlage, auf denen eine Verarbeitung beruht, entnehmen Sie dieser Datenschutzerkl\u00e4rung. Wenn Sie Widerspruch einlegen, werden wir Ihre betroffenen personenbezogenen Daten nicht mehr verarbeiten, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die Ihre Interessen, Rechte und Freiheiten \u00fcberwiegen oder die Verarbeitung dient der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen (Widerspruch nach Art. 21 Abs. 1 DSGVO).<\/p>\n<p>Werden Ihre personenbezogenen Daten verarbeitet, um Direktwerbung zu betreiben, so haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung Sie betreffender personenbezogener Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht. Wenn Sie widersprechen, werden Ihre personenbezogenen Daten anschlie\u00dfend nicht mehr zum Zwecke der Direktwerbung verwendet (Widerspruch nach Art. 21 Abs. 2 DSGVO).<\/p>\n<p class=\"Text-Title\"><strong>Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde<\/strong><\/p>\n<p>Im Falle von Verst\u00f6\u00dfen gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedsstaat ihres gew\u00f6hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des Mutma\u00dflichen Versto\u00dfes zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p>\n<p class=\"Text-Title\"><strong>SSL- bzw. TLS-Verschl\u00fcsselung<\/strong><\/p>\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL-bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201chttp:\/\/\u201d auf \u201chttps:\/\/\u201d wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n<p>Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"Text-title\">Datenerfassung auf unserer Website<\/h3>\n<p>&nbsp;<\/p>\n<p><strong>Beschreibung und Umfang der Datenverarbeitung<\/strong><\/p>\n<p>Bei jedem Aufruf unserer Internetseite erfasst unser System automatisiert Daten und Informationen, die durch den auf Ihrem Endger\u00e4t zum Einsatz kommenden Browser an den Server unserer Internetseite gesendet werden. Folgende Daten werden ohne Ihr Zutun erhoben und bis zur automatisierten L\u00f6schung gespeichert:<br \/>\n\u2013 Informationen \u00fcber den Browsertyp und die verwendete Version sowie \u00fcber das Betriebssystem und Ihren Internet-Service-Provider<br \/>\n\u2013 Die IP-Adresse des Nutzers<br \/>\n\u2013 Datum und Uhrzeit des Zugriffs<br \/>\n\u2013 Konkrete Seite (Name und URL)<br \/>\n\u2013 Internetseite, von der aus Sie auf unsere Internetseite gelangen<br \/>\n\u2013 Internetseite, die \u00fcber unsere Internetseite aufgerufen wird<br \/>\nDiese Daten werden vor\u00fcbergehend in den Logfiles unseres Systems gespeichert. Nicht hiervon betroffen ist Ihre IP-Adresse.<br \/>\nEine \u00fcber die vor\u00fcbergehende Speicherung in den Logfiles hinausgehende Speicherung der Daten zusammen mit anderen personenbezogenen Daten des Nutzers findet nicht statt.<\/p>\n<p><strong>Rechtsgrundlage f\u00fcr die Datenverarbeitung<\/strong><\/p>\n<p>Rechtsgrundlage f\u00fcr die vor\u00fcbergehende Speicherung der Daten ist Art. 6 Abs. 1 lit. f DSGVO.<\/p>\n<p><strong>Zweck der Datenverarbeitung<\/strong><\/p>\n<p>Die vor\u00fcbergehende Speicherung der IP-Adresse durch das System ist notwendig, um eine Auslieferung der Website an Ihren Rechner zu erm\u00f6glichen. Hierf\u00fcr muss Ihre IP-Adresse f\u00fcr die Dauer der Sitzung gespeichert bleiben.<br \/>\nDie Speicherung in Logfiles erfolgt, um die Funktionsf\u00e4higkeit der Internetseite sicherzustellen. Zudem dienen uns die Daten zur Optimierung der Internetseite und zur Sicherstellung der Sicherheit unserer Systeme.<br \/>\nIn diesen Zwecken liegt auch unser berechtigtes Interesse an der Datenverarbeitung nach Art. 6 Abs. 1 lit. f DSGVO.<\/p>\n<p><strong>Dauer der Speicherung<\/strong><\/p>\n<p>Die Daten werden gel\u00f6scht, sobald sie f\u00fcr die Erreichung des Zweckes ihrer Erhebung nicht mehr erforderlich sind. Im Falle der Erfassung der Daten zur Bereitstellung der Internetseite ist dies der Fall, wenn die jeweilige Sitzung beendet ist.<\/p>\n<p><strong>Widerspruchs- und Beseitigungsm\u00f6glichkeit<\/strong><\/p>\n<p>Die Erfassung der Daten zur Bereitstellung der Website und die Speicherung der Daten in Logfiles ist f\u00fcr den Betrieb der Internetseite zwingend erforderlich. Es besteht folglich seitens des Nutzers keine Widerspruchsm\u00f6glichkeit.<\/p>\n<p><strong>Einsatz von Cookies<\/strong><\/p>\n<p>Beschreibung und Umfang der Datenverarbeitung<br \/>\nDiese Internetseite benutzt Google Analytics, einen Webanalysedienst der Google Inc. (\u201eGoogle\u201c). Google Analytics verwendet sog. \u201eCookies\u201c. Das sind Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Internetseite durch Sie erm\u00f6glichen. Die durch das Cookie erzeugten Informationen \u00fcber Ihre Benutzung der Internetseite wie Browser-Typ\/-Version, verwendetes Betriebssystem, Referrer-URL (die zuvor besuchte Seite), Hostname des zugreifenden Rechners (IP- Adresse), Uhrzeit der Serveranfrage, werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt. Wir haben zudem auf dieser Internetseite Google Analytics um den Code \u201eanonymizeIP\u201c erweitert. Dies garantiert die Maskierung Ihrer IP-Adresse, sodass alle Daten anonym erhoben werden. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt.<br \/>\nIn unserem Auftrag wird Google diese Informationen benutzen, um Ihre Nutzung der Internetseite auszuwerten, um Reports \u00fcber die Internetseiten-Aktivit\u00e4ten zusammenzustellen und um weitere mit der Internetseiten-Nutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber uns zu erbringen.<\/p>\n<p><strong>Rechtsgrundlage f\u00fcr die Datenverarbeitung<\/strong><\/p>\n<p>Die Rechtsgrundlage f\u00fcr die Verarbeitung personenbezogener Daten unter Verwendung von Cookies ist Art. 6 Abs. 1 lit. f DSGVO. Das berechtigte Interesse folgt aus den nachfolgenden Zwecken der Datenverarbeitung.<\/p>\n<p><strong>Zwecke der Datenverarbeitung<\/strong><\/p>\n<p>Der Zweck der Verwendung ist es, die Nutzung von Internetseiten f\u00fcr die Nutzer zu vereinfachen. Einige Funktionen unserer Internetseite k\u00f6nnen ohne den Einsatz von Cookies nicht angeboten werden. F\u00fcr diese ist es erforderlich, dass der Browser auch nach einem Wechsel der Internetseite wiedererkannt wird.<br \/>\nDie Verwendung der Cookies erfolgt dar\u00fcber hinaus zu dem Zweck, die Qualit\u00e4t unserer Internetseite und deren Inhalte zu verbessern. Durch diese \u201eAnalyse-Cookies\u201c erfahren wir, wie die Internetseite genutzt wird und k\u00f6nnen so unser Angebot stetig optimieren.<\/p>\n<p><strong>Dauer der Speicherung, Widerspruchs- und Beseitigungsm\u00f6glichkeit<\/strong><\/p>\n<p>Cookies werden auf Ihrem Rechner gespeichert und von diesem an unsere Internetseite \u00fcbermittelt. Daher haben Sie als Nutzer auch die volle Kontrolle \u00fcber die Verwendung von Cookies. Durch eine \u00c4nderung der Einstellungen in Ihrem Internetbrowser k\u00f6nnen Sie die Speicherung von Cookies deaktivieren oder einschr\u00e4nken. Bereits gespeicherte Cookies k\u00f6nnen jederzeit gel\u00f6scht werden. Dies kann auch automatisiert erfolgen. Werden Cookies f\u00fcr unsere Internetseite deaktiviert, k\u00f6nnen m\u00f6glicherweise nicht mehr alle Funktionen der Internetseite vollumf\u00e4nglich genutzt werden.<br \/>\nSie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch das Cookie erzeugten und auf Ihre Nutzung der Internetseite bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren: Browser-Add-On zur Deaktivierung von Google Analytics. Alternativ zum Browser-Add-On, insbesondere bei Browsern auf mobilen Endger\u00e4ten, k\u00f6nnen Sie die Erfassung durch Google Analytics zudem verhindern, indem Sie auf diesen Link klicken. Dabei wird ein Opt-Out-Cookie auf Ihrem Ger\u00e4t installiert. Damit wird die Erfassung durch Google<br \/>\nAnalytics f\u00fcr diese Internetseite und f\u00fcr diesen Browser zuk\u00fcnftig verhindert, so lange das Cookie in Ihrem Browser installiert bleibt.<\/p>\n<p class=\"adsimple-311195824\" data-fontsize=\"24\" data-lineheight=\"36\"><strong>Newsletter<\/strong><\/p>\n<p><span class=\"adsimple-311195824\">Wenn Sie sich f\u00fcr unseren Newsletter eintragen \u00fcbermitteln Sie pers\u00f6nliche Daten und geben uns das Recht Sie per E-Mail zu kontaktieren. Die im Rahmen der Anmeldung zum Newsletter gespeicherten Daten nutzen wir ausschlie\u00dflich f\u00fcr unseren Newsletter und geben diese nicht weiter.<\/span><\/p>\n<p><span class=\"adsimple-311195824\">Sollten Sie sich vom Newsletter abmelden \u2013 Sie finden den Link daf\u00fcr in jedem Newsletter ganz unten \u2013 dann l\u00f6schen wir alle Daten die mit der Anmeldung zum Newsletter gespeichert wurden.<\/span><\/p>\n<p><strong>Kontaktformular<\/strong><\/p>\n<p><strong>Beschreibung und Umfang der Datenverarbeitung<\/strong><\/p>\n<p>Auf unserer Internetseite ist ein Kontaktformular vorhanden, welches f\u00fcr die elektronische Kontaktaufnahme genutzt werden kann. Nimmt ein Nutzer diese M\u00f6glichkeit wahr, so werden die in der Eingabemaske eingegeben Daten verschl\u00fcsselt an uns \u00fcbermittelt und gespeichert. Diese Daten sind:<br \/>\n\u2013 Betreff<br \/>\n\u2013 Ihr Name (Pflichtfeld)<br \/>\n\u2013 Ihre E-Mail-Adresse (Pflichtfeld)<br \/>\n\u2013 Ihre Telefonnummer<br \/>\n\u2013 Ihre Nachricht<br \/>\nIm Zeitpunkt der Absendung werden zudem Ihre IP-Adresse und das Datum und die Uhrzeit gespeichert.<\/p>\n<p><strong>Rechtsgrundlage f\u00fcr die Datenverarbeitung<\/strong><\/p>\n<p>Rechtsgrundlage f\u00fcr die Verarbeitung der Daten ist bei Vorliegen einer Einwilligung des Nutzers Art. 6 Abs. 1 lit. a DSGVO.<\/p>\n<p><strong>Zweck der Datenverarbeitung<\/strong><\/p>\n<p>Die Verarbeitung der personenbezogenen Daten aus der Eingabemaske dient uns allein zur Bearbeitung der Kontaktaufnahme.<br \/>\nDie sonstigen w\u00e4hrend des Absendevorgangs verarbeiteten personenbezogenen Daten dienen dazu, einen Missbrauch des Kontaktformulars zu verhindern und die Sicherheit unserer informationstechnischen Systeme sicherzustellen.<\/p>\n<p><strong>Dauer der Speicherung<\/strong><\/p>\n<p>Die Daten werden gel\u00f6scht, sobald sie f\u00fcr die Erreichung des Zweckes ihrer Erhebung nicht mehr erforderlich sind. F\u00fcr die personenbezogenen Daten aus der Eingabemaske des Kontaktformulars, ist dies dann der Fall, wenn die jeweilige Konversation mit Ihnen beendet ist.<br \/>\nDie w\u00e4hrend des Absendevorgangs zus\u00e4tzlich erhobenen personenbezogenen Daten werden sp\u00e4testens nach einer Frist von drei\u00dfig Tagen gel\u00f6scht.<\/p>\n<p><strong>Widerspruchs- und Beseitigungsm\u00f6glichkeit<\/strong><\/p>\n<p>Sie haben jederzeit die M\u00f6glichkeit, ihre Einwilligung zur Verarbeitung der personenbezogenen Daten zu widerrufen. In einem solchen Fall kann die Konversation nicht fortgef\u00fchrt werden.<br \/>\nHierf\u00fcr senden Sie uns bitte eine E-Mail an\u00a0<span id=\"eeb-818816-196740\">info@kanzlei-taner.de<\/span>.<br \/>\nAlle personenbezogenen Daten, die im Zuge der Kontaktaufnahme mittels E-Mail gespeichert wurden, werden in diesem Fall gel\u00f6scht.<\/p>\n<p><strong>Kontaktaufnahme mittels E-Mail<\/strong><\/p>\n<p>Sofern Sie \u00fcber eine der von uns bereitgestellten E-Mail-Adressen Kontakt zu uns aufnehmen, werden die von Ihnen mitgeteilten Informationen und personenbezogenen Daten ausschlie\u00dflich zum Zwecke der Bearbeitung Ihrer jeweiligen Anfrage verarbeitet.<br \/>\nRechtsgrundlage f\u00fcr die Verarbeitung der Daten, die im Zuge einer \u00dcbersendung einer E-Mail \u00fcbermittelt werden, ist Art. 6 Abs. 1 lit. f DSGVO. Zielt der E-Mail-Kontakt auf den Abschluss eines Vertrages ab, so ist zus\u00e4tzliche Rechtsgrundlage f\u00fcr die Verarbeitung Art. 6 Abs. 1 lit. b DSGVO.<br \/>\nDie Daten werden gel\u00f6scht, sobald sie f\u00fcr die Erreichung des Zweckes ihrer Erhebung nicht mehr erforderlich sind. F\u00fcr die personenbezogenen Daten, die Sie uns per E-Mail \u00fcbersandt haben, ist dies dann der Fall, wenn die jeweilige Konversation mit Ihnen beendet ist.<br \/>\nSie haben jederzeit die M\u00f6glichkeit, ihre Einwilligung zur Verarbeitung der personenbezogenen Daten zu widerrufen. In einem solchen Fall kann die Konversation nicht fortgef\u00fchrt werden. Hierf\u00fcr senden Sie uns bitte eine E-Mail an\u00a0<span id=\"eeb-679434-309563\">info@kanzlei-taner.de<\/span>.<br \/>\nAlle personenbezogenen Daten, die im Zuge der Kontaktaufnahme mittels E-Mail gespeichert wurden, werden in diesem Fall gel\u00f6scht.<\/p>\n<p><strong>Rechte der betroffenen Person<\/strong><\/p>\n<p>Werden personenbezogene Daten von Ihnen verarbeitet, sind Sie Betroffener i.S.d. DSGVO und es stehen Ihnen folgende Rechte zu:<\/p>\n<p><strong>Auskunftsrecht<\/strong><\/p>\n<p>Sie k\u00f6nnen von uns gem\u00e4\u00df Art. 15 DSGVO Auskunft \u00fcber Ihre von uns verarbeiteten personenbezogene Daten verlangen. Ihr Auskunftsrecht umfasst insbesondere die nachfolgenden Informationen:<br \/>\n\u2013 Verarbeitungszwecke<br \/>\n\u2013 die Kategorie der personenbezogenen Daten<br \/>\n\u2013 die Kategorien von Empf\u00e4ngern, gegen\u00fcber denen Ihre Daten offengelegt wurden oder werden<br \/>\n\u2013 die geplante Speicherdauer<br \/>\n\u2013 das Bestehen eines Rechts auf Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung oder Widerspruch<br \/>\n\u2013 das Bestehen eines Beschwerderechts<br \/>\n\u2013 die Herkunft ihrer Daten, sofern diese nicht bei uns erhoben wurden<br \/>\n\u2013 das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling und ggf. aussagekr\u00e4ftigen Informationen zu deren Einzelheiten<br \/>\n\u2013 ob die Sie betreffenden personenbezogenen Daten in ein Drittland oder an eine internationale Organisation \u00fcbermittelt werden; in diesem Zusammenhang k\u00f6nnen Sie verlangen, \u00fcber die geeigneten Garantien gem. Art. 46 DSGVO im Zusammenhang mit der \u00dcbermittlung unterrichtet zu werden<\/p>\n<p><strong>Recht auf Berichtigung<\/strong><\/p>\n<p>Sie haben gem\u00e4\u00df Art. 16 DSGVO das Recht, unverz\u00fcglich die Berichtigung unrichtiger oder Vervollst\u00e4ndigung Ihrer bei uns gespeicherten personenbezogenen Daten zu verlangen.<\/p>\n<p><strong>Recht auf L\u00f6schung<\/strong><\/p>\n<p>Sie haben gem\u00e4\u00df Art. 17 DSGVO das Recht, die unverz\u00fcgliche L\u00f6schung Ihrer bei uns gespeicherten personenbezogenen Daten zu verlangen, sofern einer der folgenden Gr\u00fcnde zutrifft:<br \/>\n\u2013 die Sie betreffenden personenbezogenen Daten sind f\u00fcr die Zwecke, f\u00fcr die sie erhoben oder auf sonstige Weise verarbeitet wurden, nicht mehr notwendig<br \/>\n\u2013 Sie widerrufen Ihre Einwilligung, auf die sich die Verarbeitung gem. Art. 6 Abs. 1 lit. a oder Art. 9 Abs. 2 lit. a DSGVO st\u00fctzte, und es fehlt an einer anderweitigen Rechtsgrundlage f\u00fcr die Verarbeitung<br \/>\n\u2013 Sie legen gem. Art. 21 Abs. 1 DSGVO Widerspruch gegen die Verarbeitung ein und es liegen keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vor, oder Sie legen gem. Art. 21 Abs. 2 DSGVO Widerspruch gegen die Verarbeitung ein<br \/>\n\u2013 die Sie betreffenden personenbezogenen Daten wurden unrechtm\u00e4\u00dfig verarbeitet<br \/>\n\u2013 die L\u00f6schung der Sie betreffenden personenbezogenen Daten ist zur Erf\u00fcllung einer rechtlichen Verpflichtung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten erforderlich, dem der Verantwortliche unterliegt<br \/>\n\u2013 die Sie betreffenden personenbezogenen Daten wurden in Bezug auf angebotene Dienste der Informationsgesellschaft gem\u00e4\u00df Art. 8 Abs. 1 DSGVO erhoben.<br \/>\nSie k\u00f6nnen die L\u00f6schung nicht verlangen, soweit die Verarbeitung zur Aus\u00fcbung des Rechts auf freie Meinungs\u00e4u\u00dferung und Information, zur Erf\u00fcllung einer rechtlichen Verpflichtung, aus Gr\u00fcnden des \u00f6ffentlichen Interesses oder zur Geltendmachung oder zur Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen erforderlich ist.<\/p>\n<p><strong>Recht auf Einschr\u00e4nkung der Verarbeitung<\/strong><\/p>\n<p>Sie haben gem\u00e4\u00df Art. 18 DSGVO das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen,<br \/>\n\u2013 soweit die Richtigkeit der Daten von Ihnen f\u00fcr eine Dauer bestritten wird, die es uns erm\u00f6glicht, die personenbezogenen Daten zu \u00fcberpr\u00fcfen,<br \/>\n\u2013 die Verarbeitung unrechtm\u00e4\u00dfig ist, Sie aber deren L\u00f6schung ablehnen,<br \/>\n\u2013 wir die Daten nicht mehr ben\u00f6tigen, Sie jedoch diese zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen ben\u00f6tigen, oder<br \/>\n\u2013 Sie gem\u00e4\u00df Art. 21 DSGVO Widerspruch gegen die Verarbeitung eingelegt haben und noch nicht feststeht, ob unsere berechtigten Gr\u00fcnde die Ihren \u00fcberwiegen.<\/p>\n<p><strong>Recht auf Unterrichtung<\/strong><\/p>\n<p>Sie haben gem\u00e4\u00df Art. 19 DSGVO das Recht, \u00fcber Empf\u00e4nger, denen eine Berichtigung oder L\u00f6schung der Daten oder Einschr\u00e4nkung der Verarbeitung von uns mitgeteilt wurde, auf Ihr Verlangen hin unterrichtet zu werden.<\/p>\n<p><strong>Recht auf Daten\u00fcbertragbarkeit<\/strong><\/p>\n<p>Sie haben gem\u00e4\u00df Art. 20 DSGVO das Recht, die Sie betreffenden personenbezogenen Daten, die Sie uns bereitgestellt haben, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten. Au\u00dferdem haben Sie das Recht, diese Daten einem anderen Verantwortlichen zu \u00fcbermitteln oder von uns die \u00dcbermittlung an einen anderen Verantwortlichen zu verlangen, soweit dies technisch machbar ist.<br \/>\nFreiheiten und Rechte anderer Personen d\u00fcrfen hierdurch nicht beeintr\u00e4chtigt werden.<\/p>\n<p><strong>Widerspruchsrecht<\/strong><\/p>\n<p>Sie haben gem\u00e4\u00df Art. 21 DSGVO das Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten, die aufgrund von Art. 6 Abs. 1 lit. e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling.<\/p>\n<p><strong>Recht auf Widerruf der datenschutzrechtlichen Einwilligungserkl\u00e4rung<\/strong><\/p>\n<p>Sie haben gem\u00e4\u00df Art. 7 Abs. 3 das Recht, Ihre datenschutzrechtliche Einwilligungserkl\u00e4rung jederzeit zu widerrufen. Durch den Widerruf der Einwilligung wird die Rechtm\u00e4\u00dfigkeit der aufgrund der Einwilligung bis zum Widerruf erfolgten Verarbeitung nicht ber\u00fchrt.<\/p>\n<p>Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde<\/p>\n<p>Sie haben gem\u00e4\u00df Art. 77 DSGVO das Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres Aufenthaltsorts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><!-- \/.sc_content --><div class=\"vc_empty_space\"   style=\"height: 4em\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12 sc_layouts_column_icons_position_left\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 70px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"Datenschutz Allgemeine Hinweise &nbsp; Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer Website Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser&hellip;","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutz - Kanzlei-Taner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kanzlei-taner.de\/tr\/contacts\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - Kanzlei-Taner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kanzlei-taner.de\/tr\/contacts\/\" \/>\n<meta property=\"og:site_name\" content=\"Kanzlei-Taner\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-17T20:01:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kanzlei-taner.de\/#website\",\"url\":\"https:\/\/kanzlei-taner.de\/\",\"name\":\"Kanzlei-Taner\",\"description\":\"Rechtsanw\u00e4ltin Sevinc Taner Oezbelli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kanzlei-taner.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"tr\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kanzlei-taner.de\/tr\/contacts\/#webpage\",\"url\":\"https:\/\/kanzlei-taner.de\/tr\/contacts\/\",\"name\":\"Datenschutz - Kanzlei-Taner\",\"isPartOf\":{\"@id\":\"https:\/\/kanzlei-taner.de\/#website\"},\"datePublished\":\"2017-04-06T12:52:51+00:00\",\"dateModified\":\"2021-10-17T20:01:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/kanzlei-taner.de\/tr\/contacts\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kanzlei-taner.de\/tr\/contacts\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kanzlei-taner.de\/tr\/contacts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/kanzlei-taner.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - Kanzlei-Taner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kanzlei-taner.de\/tr\/contacts\/","og_locale":"tr_TR","og_type":"article","og_title":"Datenschutz - Kanzlei-Taner","og_url":"https:\/\/kanzlei-taner.de\/tr\/contacts\/","og_site_name":"Kanzlei-Taner","article_modified_time":"2021-10-17T20:01:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tahmini okuma s\u00fcresi":"16 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/kanzlei-taner.de\/#website","url":"https:\/\/kanzlei-taner.de\/","name":"Kanzlei-Taner","description":"Rechtsanw\u00e4ltin Sevinc Taner Oezbelli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kanzlei-taner.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"tr"},{"@type":"WebPage","@id":"https:\/\/kanzlei-taner.de\/tr\/contacts\/#webpage","url":"https:\/\/kanzlei-taner.de\/tr\/contacts\/","name":"Datenschutz - Kanzlei-Taner","isPartOf":{"@id":"https:\/\/kanzlei-taner.de\/#website"},"datePublished":"2017-04-06T12:52:51+00:00","dateModified":"2021-10-17T20:01:18+00:00","breadcrumb":{"@id":"https:\/\/kanzlei-taner.de\/tr\/contacts\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kanzlei-taner.de\/tr\/contacts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kanzlei-taner.de\/tr\/contacts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kanzlei-taner.de\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]}]}},"_links":{"self":[{"href":"https:\/\/kanzlei-taner.de\/tr\/wp-json\/wp\/v2\/pages\/76"}],"collection":[{"href":"https:\/\/kanzlei-taner.de\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kanzlei-taner.de\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kanzlei-taner.de\/tr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kanzlei-taner.de\/tr\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":0,"href":"https:\/\/kanzlei-taner.de\/tr\/wp-json\/wp\/v2\/pages\/76\/revisions"}],"wp:attachment":[{"href":"https:\/\/kanzlei-taner.de\/tr\/wp-json\/wp\/v2\/media?parent=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}